{"id":5170,"date":"2025-12-26T07:00:00","date_gmt":"2025-12-26T07:00:00","guid":{"rendered":"https:\/\/perspetivaatual.pt\/?p=5170"},"modified":"2025-12-17T15:14:53","modified_gmt":"2025-12-17T15:14:53","slug":"centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao","status":"publish","type":"post","link":"https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/","title":{"rendered":"Centro de Tratamento Cir\u00fargico do Linfedema em Portugal: \u201cDar esperan\u00e7a onde antes havia apenas resigna\u00e7\u00e3o\u201d"},"content":{"rendered":"\n<p><strong>A vis\u00e3o pioneira do Dr. Gustavo Coelho no Hospital da Vener\u00e1vel Ordem Terceira de S\u00e3o Francisco do Porto.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>O Pioneirismo do Dr. Gustavo Coelho no Tratamento do Linfedema em Portugal<\/strong><\/h2>\n\n\n\n<p>O linfedema \u00e9 uma doen\u00e7a cr\u00f3nica, progressiva e altamente incapacitante, que afeta milhares de pessoas em Portugal. Associado frequentemente \u00e0 sequela de tratamentos oncol\u00f3gicos \u2014 como o cancro da mama \u2014, ou a causas cong\u00e9nitas e traum\u00e1ticas, o linfedema foi durante d\u00e9cadas uma patologia negligenciada no nosso pa\u00eds, sobretudo no que diz respeito a solu\u00e7\u00f5es cir\u00fargicas avan\u00e7adas. Uma condi\u00e7\u00e3o cr\u00f3nica, progressiva e incapacitante, que tantas vezes roubava mobilidade, confian\u00e7a e qualidade de vida &#8211; sem alternativas reais.<\/p>\n\n\n\n<p>Em Portugal, n\u00e3o existe ainda um registo nacional espec\u00edfico, mas estima-se que entre 1.400 e 1.800 novos casos de linfedema surjam todos os anos apenas ap\u00f3s o tratamento do cancro da mama, representando cerca de 20% a 25% das mulheres que passam por cirurgia e radioterapia. Quando se incluem outros tipos de cancro e causas n\u00e3o oncol\u00f3gicas, o total pode ultrapassar 2.000 novos casos anuais.<\/p>\n\n\n\n<p>Nos \u00faltimos anos, a cirurgia linf\u00e1tica &#8211; atrav\u00e9s de t\u00e9cnicas como as anastomoses linf\u00e1tico-venosas e o transplante de g\u00e2nglios linf\u00e1ticos \u2014 tem demonstrado resultados muito positivos: cerca de 80% dos doentes apresentam redu\u00e7\u00e3o vis\u00edvel do incha\u00e7o, 70% a 90% relatam melhoria global dos sintomas e mais de 75% deixam de sofrer infe\u00e7\u00f5es recorrentes como a erisipela.<\/p>\n\n\n\n<figure class=\"wp-block-image alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"543\" height=\"568\" src=\"http:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Untitled-1.jpg\" alt=\"\" class=\"wp-image-5175\" style=\"width:278px;height:auto\" srcset=\"https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Untitled-1.jpg 543w, https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Untitled-1-287x300.jpg 287w\" sizes=\"auto, (max-width: 543px) 100vw, 543px\" \/><figcaption class=\"wp-element-caption\">Gustavo Coelho &#8211; Especialista em Cirurgia Pl\u00e1stica Reconstrutiva Est\u00e9tica no Hospital da Vener\u00e1vel Ordem Terceira de S\u00e3o Francisco do Porto<\/figcaption><\/figure>\n\n\n\n<p>Foi neste cen\u00e1rio que o Dr. Gustavo Coelho, cirurgi\u00e3o pl\u00e1stico portugu\u00eas, decidiu marcar a diferen\u00e7a. H\u00e1 mais de uma d\u00e9cada, abra\u00e7ou uma miss\u00e3o: colocar o linfedema no centro das prioridades de sa\u00fade do pa\u00eds. E trouxe para Portugal solu\u00e7\u00f5es cir\u00fargicas inovadoras que apenas estavam acess\u00edveis em grandes centros internacionais, assumindo um papel pioneiro no cen\u00e1rio nacional.<\/p>\n\n\n\n<p>Nascido em Viana do Castelo, com 43 anos, escolheu fazer a especialidade de Cirurgia Pl\u00e1stica, Reconstrutiva e Est\u00e9tica no Centro Hospitalar de Vila Nova de Gaia, em 2009, e aqui prosseguir profissionalmente, contando j\u00e1 com mais de 15 anos na institui\u00e7\u00e3o.<\/p>\n\n\n\n<p>No ano de 2012, foi a sua experi\u00eancia num est\u00e1gio em Taiwan num dos melhores centros mundiais de micro e supermicrocirurgia reconstrutiva, que lhe proporcionou o primeiro contacto e consequente despertar do interesse pela patologia do Linfedema. Ao sentir que n\u00e3o existia nenhum tratamento direcionado para estes casos no nosso Pa\u00eds, verificou que poderia fazer a diferen\u00e7a e devolver alguma esperan\u00e7a a estes doentes.<\/p>\n\n\n\n<p>Com uma forma\u00e7\u00e3o s\u00f3lida em super e microcirurgia reconstrutiva e em t\u00e9cnicas linf\u00e1ticas avan\u00e7adas adquirida em centros internacionais de refer\u00eancia, o Dr. Gustavo Coelho tornou-se um dos primeiros cirurgi\u00f5es portugueses a realizar procedimentos modernos e altamente diferenciados para melhoria da drenagem linf\u00e1tica.<\/p>\n\n\n\n<p>Hoje, \u00e9 reconhecido como pioneiro nacional no tratamento cir\u00fargico do linfedema \u2014 e uma refer\u00eancia incontorn\u00e1vel na Europa neste campo em ascens\u00e3o.<\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>Dr. Gustavo Coelho Especialista em Cirurgia Pl\u00e1stica Reconstrutiva Est\u00e9tica no Hospital da Vener\u00e1vel Ordem Terceira de S\u00e3o Francisco do Porto<\/em> <em>&#8211; Tratamento Cir\u00fargico<br>do Linfedema em Portugal: O Percurso Pioneiro do Dr. Gustavo Coelho<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\">O PRIMEIRO CENTRO DE LINFEDEMA E LIPEDEMA DO PA\u00cdS<\/h2>\n\n\n\n<p>Consciente da necessidade urgente de uma resposta multidisciplinar e organizada para esta popula\u00e7\u00e3o, o Dr. Gustavo Coelho liderou a cria\u00e7\u00e3o do primeiro Centro de Linfedema e Lipedema em Portugal, sediado no Hospital da Vener\u00e1vel Ordem Terceira de S\u00e3o Francisco do Porto \u2013 primeiro Hospital Privado na Europa a ser certificado pelo EBOPRAS (European Board of Plastic Reconstructive and Aesthetic Surgery), tornando-se uma refer\u00eancia nacional e internacional no diagn\u00f3stico, acompanhamento e tratamento integral destas patologias.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1306\" src=\"http:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Acr230659875520-483317.jpg\" alt=\"\" class=\"wp-image-5177\" style=\"width:474px;height:auto\" srcset=\"https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Acr230659875520-483317.jpg 1200w, https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Acr230659875520-483317-276x300.jpg 276w, https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Acr230659875520-483317-941x1024.jpg 941w, https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Acr230659875520-483317-768x836.jpg 768w, https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Acr230659875520-483317-1024x1114.jpg 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<p>Neste centro, cirurgia, consulta especializada, terapias descongestionantes e investiga\u00e7\u00e3o cl\u00ednica caminham lado a lado, oferecendo aos doentes acesso a cuidados modernos sem necessidade de recorrer ao estrangeiro.<\/p>\n\n\n\n<p>O Hospital da Vener\u00e1vel Ordem Terceira de S\u00e3o Francisco do Porto tem vindo a refor\u00e7ar a sua aposta na \u00e1rea do linfedema, disponibilizando servi\u00e7os especializados dedicados ao diagn\u00f3stico, tratamento e acompanhamento desta condi\u00e7\u00e3o cr\u00f3nica. Com uma equipa multidisciplinar altamente qualificada, o hospital investe em terapias de vanguarda, programas personalizados de reabilita\u00e7\u00e3o e tecnologias inovadoras que contribuem para a melhoria significativa da qualidade de vida dos pacientes.<\/p>\n\n\n\n<p>Esta aposta reflete o compromisso da institui\u00e7\u00e3o em oferecer cuidados de excel\u00eancia, promover a literacia em sa\u00fade e responder \u00e0s necessidades crescentes de quem vive com linfedema, garantindo acesso a tratamentos eficazes e humanizados.<\/p>\n\n\n\n<p><strong>Pela primeira vez, estes doentes n\u00e3o precisam de sair do pa\u00eds para encontrar tratamento eficaz.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Cirurgia Linf\u00e1tica: devolver autonomia<\/h3>\n\n\n\n<p>O Dr. Gustavo Coelho introduziu em Portugal t\u00e9cnicas microcir\u00fargicas altamente especializadas, que restauram o trajeto natural da linfa:<br>\u2013 Transfer\u00eancia de g\u00e2nglios linf\u00e1ticos vascularizados (VLNT);<br>\u2013 Anastomoses linf\u00e1tico-venosas (LVA);<br>\u2013 Microcirurgia linf\u00e1tica minimamente invasiva.<\/p>\n\n\n\n<p>O resultado tem sido transformador:<br>\u2013 Menos dor e peso nos membros;<br>\u2013 Menos infe\u00e7\u00f5es recorrentes;<br>\u2013 Maior mobilidade e independ\u00eancia;<br>\u2013 Melhor bem-estar f\u00edsico e emocional.<\/p>\n\n\n\n<p>Embora Portugal ainda n\u00e3o disponha de dados nacionais exatos e recentes para o n\u00famero de casos de linfedema, estima-se que existam cerca de 1.400 a 2.000 novos casos por ano. Este dado sugere que o linfedema constitui um problema relevante de sa\u00fade p\u00fablica que exige resposta estruturada.<\/p>\n\n\n\n<p>Estas abordagens inovadoras t\u00eam permitido melhorar drasticamente a qualidade de vida de doentes previamente sem alternativas terap\u00eauticas eficazes, reduzindo o volume do membro afetado, a frequ\u00eancia de infe\u00e7\u00f5es, a limita\u00e7\u00e3o funcional e promovendo a melhoria da qualidade de vida.<\/p>\n\n\n\n<p>Gra\u00e7as ao seu contributo cl\u00ednico e cient\u00edfico, a realidade portuguesa come\u00e7ou a mudar: o linfedema \u2014 outrora invis\u00edvel \u2014 passou a ter voz, estrutura de resposta e perspetiva de esperan\u00e7a para quem dele sofre.<\/p>\n\n\n\n<p>O compromisso cont\u00ednuo do Dr. Gustavo Coelho com o avan\u00e7o t\u00e9cnico e humanizado do tratamento do linfedema coloca Portugal no mapa europeu da cirurgia linf\u00e1tica, garantindo que os doentes t\u00eam, finalmente, acesso \u00e0 inova\u00e7\u00e3o, dignidade e qualidade de vida.<\/p>\n\n\n\n<p>\u201c\u00c9 devolver \u00e0s pessoas a liberdade de usar o seu pr\u00f3prio corpo\u201d, afirma o cirurgi\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Onde a Oncologia e a Reconstru\u00e7\u00e3o se encontram<\/strong><\/h3>\n\n\n\n<p>Como um dos respons\u00e1veis do Grupo de Senologia e Cirurgia Oncopl\u00e1stica Mam\u00e1ria do Centro Hospitalar Vila Nova de Gaia\/Espinho, o contacto do Dr. Gustavo Coelho com doentes com cancro da mama tornou ainda mais clara uma necessidade urgente:<br>\u2013 N\u00e3o chega tratar o cancro;<br>\u2013 \u00c9 preciso prevenir as sequelas que ficam para tr\u00e1s.<\/p>\n\n\n\n<p>Por isso, o pr\u00f3ximo passo est\u00e1 em curso: implementar a profilaxia linf\u00e1tica durante a cirurgia mam\u00e1ria oncol\u00f3gica, para evitar que o linfedema surja. Um avan\u00e7o que permitir\u00e1 que mais mulheres sobrevivam\u2026 com qualidade de vida.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Uma vis\u00e3o centrada no futuro<\/strong><\/h3>\n\n\n\n<p>A atividade cient\u00edfica e formativa do Dr. Gustavo Coelho tem contribu\u00eddo para:<br>\u2013 Maior sensibiliza\u00e7\u00e3o da comunidade m\u00e9dica;<br>\u2013 Desenvolvimento de protocolos de diagn\u00f3stico precoce;<br>\u2013 Cria\u00e7\u00e3o de vias cl\u00ednicas estruturadas;<br>\u2013 Afirma\u00e7\u00e3o de Portugal como territ\u00f3rio de inova\u00e7\u00e3o em cirurgia reconstrutiva.<\/p>\n\n\n\n<p>O objetivo \u00e9 que nenhum doente fique sem tratamento eficaz por falta de conhecimento, acompanhamento ou acesso.<\/p>\n\n\n\n<p>O percurso do Dr. Gustavo Coelho assinala o in\u00edcio de uma nova era no tratamento do linfedema em Portugal.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>De \u00e1rea esquecida \u00e0 prioridade cl\u00ednica: a transforma\u00e7\u00e3o est\u00e1 em curso<\/strong><\/h3>\n\n\n\n<p>A sua atua\u00e7\u00e3o pioneira \u2014 aliando ci\u00eancia, t\u00e9cnica cir\u00fargica de exce\u00e7\u00e3o e compromisso humano \u2014 abriu portas para que milhares de pessoas tenham hoje mais mobilidade, menos dor e mais esperan\u00e7a.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Quando ningu\u00e9m olhava, ele decidiu agir<\/strong><\/h3>\n\n\n\n<p>H\u00e1 doen\u00e7as que vivem nas sombras. O linfedema era uma delas.<\/p>\n\n\n\n<p>O Dr. Gustavo Coelho trouxe-o para a luz, para a agenda cl\u00ednica e para o discurso p\u00fablico \u2014 e com isso mudou vidas, destinos e expectativas.<\/p>\n\n\n\n<p>Hoje, em Portugal, existe esperan\u00e7a.<br>E \u00e9 isso que faz a diferen\u00e7a.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Centro Europeu de Cirurgia Pl\u00e1stica Reconstrutiva Craniomaxilofacial, M\u00e3o, Microcirurgia e Est\u00e9tica do Hospital da Vener\u00e1vel Ordem Terceira de S\u00e3o Francisco do Porto<\/h2>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1075\" height=\"1163\" src=\"http:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Untitled-2.jpg\" alt=\"\" class=\"wp-image-5178\" style=\"width:415px;height:auto\" srcset=\"https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Untitled-2.jpg 1075w, https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Untitled-2-277x300.jpg 277w, https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Untitled-2-947x1024.jpg 947w, https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Untitled-2-768x831.jpg 768w, https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Untitled-2-1024x1108.jpg 1024w\" sizes=\"auto, (max-width: 1075px) 100vw, 1075px\" \/><figcaption class=\"wp-element-caption\">Hor\u00e1cio Monteiro da Costa &#8211; Diretor Cl\u00ednico do Hospital da Vener\u00e1vel Ordem Terceira de S\u00e3o Francisco do Porto<\/figcaption><\/figure>\n\n\n\n<p>A atividade da Cirurgia Pl\u00e1stica Reconstrutiva Est\u00e9tica, Hospital da Vener\u00e1vel Ordem Terceira de S\u00e3o Francisco do Porto, remonta a h\u00e1 60 anos. Ap\u00f3s 1990, o tempo ajudou a solidificar uma equipa de cirurgi\u00f5es pl\u00e1sticos reconstrutivos e est\u00e9ticos, a qual \u00e9 atualmente composta por doze elementos, que asseguram as diversas \u00e1reas cl\u00ednico-cir\u00fargicas do \u00e2mbito da especialidade, que passo a referir:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Cirurgia Oncol\u00f3gica, Est\u00e9tica e Traum\u00e1tica da Cabe\u00e7a e Pesco\u00e7o;<\/li>\n\n\n\n<li>Cirurgia Craniomaxilofacial e Ortogn\u00e1tica;<\/li>\n\n\n\n<li>Cirurgia Est\u00e9tica, Oncol\u00f3gica e Reconstrutiva da Mama;<\/li>\n\n\n\n<li>Cirurgia Est\u00e9tica, Oncol\u00f3gica, Traum\u00e1tica e Reconstrutiva da M\u00e3o;<\/li>\n\n\n\n<li>Cirurgia Est\u00e9tica, Oncol\u00f3gica, Traum\u00e1tica e Reconstrutiva do Membro Superior;<\/li>\n\n\n\n<li>Cirurgia Est\u00e9tica, Oncol\u00f3gica, Traum\u00e1tica e Reconstrutiva do Membro Inferior;<\/li>\n\n\n\n<li>Cirurgia Est\u00e9tica do Tronco e Abd\u00f3men;<\/li>\n\n\n\n<li>Lipoaspira\u00e7\u00e3o e Laser;<\/li>\n\n\n\n<li>Linfedema e Lipedema;<\/li>\n\n\n\n<li>Cirurgia Patologia Cong\u00e9nita e Pedi\u00e1trica.<\/li>\n<\/ol>\n\n\n\n<p>A atividade desenvolvida ao longo destes anos, com o crescimento e a melhoria humana e t\u00e9cnico-cient\u00edfica desta equipa, permitiu a sua Acredita\u00e7\u00e3o Europeia pelo European Board Plastic Reconstructive Aesthetic Surgery (EBOPRAS) a 11 de dezembro de 2022, data da funda\u00e7\u00e3o do Centro Europeu de Cirurgia Pl\u00e1stica Reconstrutiva Craniomaxilofacial, Microcirurgia e Est\u00e9tica do Hospital da Vener\u00e1vel Ordem Terceira de S\u00e3o Francisco de Porto (CECPRCMME).<\/p>\n\n\n\n<p>Atualmente, o CECPRCMME \u00e9 o \u00fanico Centro com Acredita\u00e7\u00e3o Europeia pelo EBOPRAS com atividade privada no territ\u00f3rio europeu.<\/p>\n\n\n\n<p>Acrescem as suas afilia\u00e7\u00f5es cient\u00edficas a diversas institui\u00e7\u00f5es a n\u00edvel nacional e europeu, nomeadamente a Universidade de Aveiro e sua Unidade de Microcirurgia e Cirurgia Experimental, European Society Plastic Reconstructive Aesthetic Surgery (ESPRAS) e European Association Plastic Surgery (EURAPS).<\/p>\n\n\n\n<p>Os n\u00edveis humanos, t\u00e9cnico-cient\u00edficos e a forma\u00e7\u00e3o m\u00e9dica cont\u00ednua dos Cirurgi\u00f5es Pl\u00e1sticos Reconstrutivos e Est\u00e9ticos foram requisitos para a sua sele\u00e7\u00e3o e s\u00e3o crit\u00e9rios para a sua manuten\u00e7\u00e3o e evolu\u00e7\u00e3o dentro desta equipa.<\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>Professor Doutor Hor\u00e1cio Monteiro da Costa<br>Diretor Cl\u00ednico do Hospital da Vener\u00e1vel Ordem Terceira de S\u00e3o Francisco do Porto<br>Fundador e Diretor do CECPRCMME<br>Professor Catedr\u00e1tico da Universidade de Aveiro<br>Coordenador da UMCE<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Muito Al\u00e9m da Est\u00e9tica: O Valor Reconstrutivo da Cirurgia Pl\u00e1stica<\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"878\" height=\"1316\" src=\"http:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Untitled-3.jpg\" alt=\"\" class=\"wp-image-5179\" style=\"width:362px;height:auto\" srcset=\"https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Untitled-3.jpg 878w, https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Untitled-3-200x300.jpg 200w, https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Untitled-3-683x1024.jpg 683w, https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Untitled-3-768x1151.jpg 768w\" sizes=\"auto, (max-width: 878px) 100vw, 878px\" \/><figcaption class=\"wp-element-caption\">Hor\u00e1cio Zenha &#8211; Especialista em Cirurgia Pl\u00e1stica Reconstrutiva Est\u00e9tica no Hospital da Vener\u00e1vel Ordem Terceira de S\u00e3o Francisco do Porto<\/figcaption><\/figure>\n\n\n\n<p>A vertente mais conhecida da cirurgia pl\u00e1stica \u00e9, sem d\u00favida, a da cirurgia est\u00e9tica. \u00c9 uma \u00e1rea que tem naturalmente grande visibilidade porque est\u00e1 muito ligada \u00e0 imagem f\u00edsica, \u00e0 melhoria da apar\u00eancia e ao rejuvenescimento, sendo amplamente divulgada nos meios de comunica\u00e7\u00e3o.<\/p>\n\n\n\n<p>No entanto, ela \u00e9 apenas uma parte do campo da cirurgia pl\u00e1stica. A palavra pl\u00e1stica vem do grego \u201cplastikos\u201d, que significa modelar ou moldar. Ou seja, trata-se da ci\u00eancia (e arte) m\u00e9dica de remodelar tecidos \u2014 seja para reparar danos ou para aperfei\u00e7oar a apar\u00eancia.<\/p>\n\n\n\n<p>As situa\u00e7\u00f5es cl\u00ednicas onde estas t\u00e9cnicas t\u00eam aplica\u00e7\u00e3o s\u00e3o diversas: desde a cirurgia facial, incluindo a cirurgia ortogn\u00e1tica e rinoplastia; \u00e0 cirurgia da m\u00e3o, com toda a sua delicadeza e import\u00e2ncia funcional; \u00e0 cirurgia dos nervos perif\u00e9ricos, com recupera\u00e7\u00e3o de paralisias; ao contorno corporal, com a cirurgia est\u00e9tica.<\/p>\n\n\n\n<p>A cirurgia pl\u00e1stica permite aliar a precis\u00e3o cient\u00edfica com a sensibilidade e sentido est\u00e9tico, sempre alicer\u00e7ada nos mais recentes avan\u00e7os tecnol\u00f3gicos. O objetivo \u00e9 sempre o mesmo: restaurar a forma e a fun\u00e7\u00e3o, promovendo n\u00e3o apenas a recupera\u00e7\u00e3o f\u00edsica, mas tamb\u00e9m o bem-estar e a confian\u00e7a de cada paciente.<\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>Dr. Hor\u00e1cio Zenha<br>Especialista em Cirurgia Pl\u00e1stica Reconstrutiva Est\u00e9tica no Hospital da Vener\u00e1vel Ordem Terceira de S\u00e3o Francisco do Porto<br>Presidente da Sociedade Portuguesa de Cirurgia Pl\u00e1stica Reconstrutiva e Est\u00e9tica<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Um Servi\u00e7o de Otorrinolaringologia moderno, seguro e de excel\u00eancia<\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"638\" height=\"527\" src=\"http:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Untitled-5.jpg\" alt=\"\" class=\"wp-image-5180\" style=\"width:444px;height:auto\" srcset=\"https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Untitled-5.jpg 638w, https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Untitled-5-300x248.jpg 300w\" sizes=\"auto, (max-width: 638px) 100vw, 638px\" \/><figcaption class=\"wp-element-caption\">Ricardo Henriques Pereira &#8211; Coordenador de Otorrinolaringologia do Hospital da Vener\u00e1vel Ordem Terceira de S\u00e3o Francisco do Porto<\/figcaption><\/figure>\n\n\n\n<p>Nos tempos que correm, num cen\u00e1rio de multiplica\u00e7\u00e3o excessiva de oferta de servi\u00e7os m\u00e9dicos privados, que privilegiam a quantidade em detrimento da qualidade, acredit\u00e1mos poder fazer mais e muito melhor. \u00c9 neste cen\u00e1rio que destacamos o Servi\u00e7o de Otorrinolaringologia, no Hospital da Vener\u00e1vel Ordem Terceira de S\u00e3o Francisco do Porto, que se distingue pela combina\u00e7\u00e3o perfeita entre tecnologia de \u00faltima gera\u00e7\u00e3o, experi\u00eancia cl\u00ednica de excel\u00eancia e um ambiente pensado para o conforto e seguran\u00e7a de cada paciente. Aqui, cada detalhe foi cuidadosamente repensado e maturado, ao longo de largas d\u00e9cadas, para assegurar um acompanhamento dos nossos clientes de alto n\u00edvel, desde a primeira consulta at\u00e9 ao p\u00f3s-tratamento. <\/p>\n\n\n\n<p>A nossa equipa de especialistas em Otorrino, criteriosamente selecionada, \u00e9 composta por m\u00e9dicos altamente qualificados, com forma\u00e7\u00e3o avan\u00e7ada nas mais modernas t\u00e9cnicas diagn\u00f3sticas e cir\u00fargicas, funcionais e est\u00e9ticas. Atrav\u00e9s de equipamentos de imagem de alta resolu\u00e7\u00e3o, endoscopia digital e sistemas cir\u00fargicos de ponta, garantimos avalia\u00e7\u00f5es precisas e interven\u00e7\u00f5es minimamente invasivas, promovendo uma recupera\u00e7\u00e3o mais r\u00e1pida e resultados superiores. No Hospital da Vener\u00e1vel Ordem Terceira de S\u00e3o Francisco do Porto, oferecemos um vasto leque de procedimentos diagn\u00f3sticos e terap\u00eauticos, constantemente inovados e atualizados, desde cirurgias funcionais do nariz e seios perinasais, ao diagn\u00f3stico e tratamento de dist\u00farbios do sono, incluindo muitos anos de experi\u00eancia nas t\u00e9cnicas de Video-sonoscopia, \u00e0 cirurgia otol\u00f3gica, com especial enfoque para os implantes auditivos, que permitem a reabilita\u00e7\u00e3o auditiva de quem muitas vezes j\u00e1 desistiu de alguma vez vir a poder ouvir, e ainda opera\u00e7\u00f5es avan\u00e7adas para corre\u00e7\u00e3o de outras altera\u00e7\u00f5es respirat\u00f3rias, altera\u00e7\u00f5es anat\u00f3micas, est\u00e9ticas e funcionais.<\/p>\n\n\n\n<p>Dedicamo-nos a acompanhar, do momento diagn\u00f3stico at\u00e9 \u00e0 reabilita\u00e7\u00e3o e recupera\u00e7\u00e3o, os doentes com qualquer tipo de surdez e de doen\u00e7as do equil\u00edbrio, estando totalmente capacitados para dar aquele apoio essencial \u00e0 reconquista da independ\u00eancia motora de cada um dos nossos clientes. Damos especial aten\u00e7\u00e3o ao rastreio do cancro da cabe\u00e7a e pesco\u00e7o, com t\u00e9cnicas de imagem actualizadas e inovadoras. Dedicamo-nos ainda ao desenvolvimento de t\u00e9cnicas de rastreio e tratamento auditivo e respirat\u00f3rio desde os primeiros dias de vida, para que nenhuma crian\u00e7a perca a sua oportunidade.<\/p>\n\n\n\n<p>Cada interven\u00e7\u00e3o \u00e9 realizada em blocos operat\u00f3rios equipados com tecnologia de ponta e apoiados por equipas multidisciplinares dedicadas. No nosso hospital, o paciente encontra n\u00e3o apenas cuidados m\u00e9dicos de refer\u00eancia, mas tamb\u00e9m um ambiente acolhedor, privativo e humanizado, destacando-se dos demais. O foco na experi\u00eancia do utente \u00e9 uma prioridade, procurando assegurar bem-estar em todas as etapas, com acompanhamento pr\u00f3ximo, informa\u00e7\u00e3o clara e apoio cont\u00ednuo.<\/p>\n\n\n\n<p>Se procura um Servi\u00e7o de Otorrinolaringologia moderno, seguro e de excel\u00eancia, somos a escolha certa. Aqui, a sua sa\u00fade est\u00e1 em m\u00e3os experientes, num espa\u00e7o onde a qualidade se une ao cuidado. Confiantes que corremos no mesmo sentido: aquele onde tudo faz sentido.<\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>Ricardo Henriques Pereira, MD, ENT<br>Especialista em Otorrinolaringologia e Cirurgia da Cabe\u00e7a e Pesco\u00e7o. Master em Medicina Est\u00e9tica<br>P\u00f3s-Gradua\u00e7\u00e3o em Dire\u00e7\u00e3o e Administra\u00e7\u00e3o de Servi\u00e7os de Sa\u00fade, FEP<br>Coordenador de Otorrinolaringologia do Hospital da Vener\u00e1vel Ordem Terceira de S\u00e3o Francisco do Porto<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Estomatologia: A especialidade centen\u00e1ria que une medicina, cirurgia e sa\u00fade oral<\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"422\" height=\"664\" src=\"http:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Untitled-4.jpg\" alt=\"\" class=\"wp-image-5181\" style=\"width:362px;height:auto\" srcset=\"https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Untitled-4.jpg 422w, https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Untitled-4-191x300.jpg 191w\" sizes=\"auto, (max-width: 422px) 100vw, 422px\" \/><figcaption class=\"wp-element-caption\">Carlos Faria &#8211; M\u00e9dico no Hospital da Vener\u00e1vel Ordem Terceira de S\u00e3o Francisco do Porto<\/figcaption><\/figure>\n\n\n\n<p>Criada em Portugal h\u00e1 mais de um s\u00e9culo por um grupo pioneiro de cirurgi\u00f5es, a Estomatologia consolidou-se como uma especialidade singular no panorama da sa\u00fade. Desde a sua origem que se dedica ao tratamento das doen\u00e7as da boca, maxilares e \u00f3rg\u00e3os anexos, mantendo-se at\u00e9 hoje como a \u00fanica especialidade m\u00e9dica que integra, de forma plena, vertentes m\u00e9dicas, cir\u00fargicas e dent\u00e1rias.<\/p>\n\n\n\n<p>Ao longo dos tempos, a Estomatologia evoluiu e modernizou-se mantendo, contudo, o seu campo de atua\u00e7\u00e3o inicial. Esta abrang\u00eancia traduz-se num leque vasto de interven\u00e7\u00f5es cl\u00ednicas e cir\u00fargicas, entre elas destacam-se a cirurgia oral e maxilar, a cirurgia ortogn\u00e1tica, a cirurgia da articula\u00e7\u00e3o temporomandibular, a reabilita\u00e7\u00e3o oral incluindo implantologia, pr\u00f3tese fixa e remov\u00edvel, e a estomatologia oncol\u00f3gica com a respetiva reabilita\u00e7\u00e3o desses doentes. Estes tratamentos podem ser realizados sob anestesia local ou geral, consoante a indica\u00e7\u00e3o de cada caso.<\/p>\n\n\n\n<p>No Hospital da Vener\u00e1vel Ordem Terceira de S\u00e3o Francisco do Porto, o Dr. Carlos Faria \u2014 m\u00e9dico e m\u00e9dico dentista \u2014 coloca esta dupla forma\u00e7\u00e3o ao servi\u00e7o dos doentes, oferecendo solu\u00e7\u00f5es diferenciadas em \u00e1reas altamente especializadas. Da sua experi\u00eancia no Servi\u00e7o de Estomatologia do Hospital de S\u00e3o Jo\u00e3o no Porto destacam-se a cirurgia ortogn\u00e1tica minimamente invasiva, a pr\u00f3tese da articula\u00e7\u00e3o temporomandibular, a cirurgia das gl\u00e2ndulas salivares e a reabilita\u00e7\u00e3o oromaxilar complexa com recurso a implantes dent\u00e1rios.<\/p>\n\n\n\n<p>Acresce na pr\u00e1tica hospitalar da Ordem de S\u00e3o Francisco, todo o estudo e planeamento cir\u00fargico baseado nos mais avan\u00e7ados meios tecnol\u00f3gicos, nomeadamente, imagem tridimensional com digitaliza\u00e7\u00e3o oral e facial e planeamento cir\u00fargico virtual, possibilitando cirurgias de alta precis\u00e3o com t\u00e9cnicas minimamente invasivas.<\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>Dr. Carlos Faria<br>M\u00e9dico no Hospital da Vener\u00e1vel Ordem Terceira de S\u00e3o Francisco do Porto<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A vis\u00e3o pioneira do Dr. Gustavo Coelho no Hospital da Vener\u00e1vel Ordem Terceira de S\u00e3o<\/p>\n","protected":false},"author":11,"featured_media":5174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,4],"tags":[162,911,915,908,910,456,909,912,913,914],"class_list":["post-5170","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-saude","tag-cirurgia-plastica","tag-cirurgia-plastica-reconstrutiva-craniomaxilofacial","tag-estomatologia","tag-gustavo-coelho","tag-horacio-costa","tag-hospital-sao-francisco-do-porto","tag-linfedema","tag-mao","tag-microcirurgia-e-estetica","tag-otorrinolaringologia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Centro de Tratamento Cir\u00fargico do Linfedema em Portugal: \u201cDar esperan\u00e7a onde antes havia apenas resigna\u00e7\u00e3o\u201d - Perspetiva Atual<\/title>\n<meta name=\"description\" content=\"A vis\u00e3o pioneira do Dr. Gustavo Coelho no Hospital da Vener\u00e1vel Ordem Terceira de S\u00e3o Francisco do Porto.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Centro de Tratamento Cir\u00fargico do Linfedema em Portugal: \u201cDar esperan\u00e7a onde antes havia apenas resigna\u00e7\u00e3o\u201d - Perspetiva Atual\" \/>\n<meta property=\"og:description\" content=\"A vis\u00e3o pioneira do Dr. Gustavo Coelho no Hospital da Vener\u00e1vel Ordem Terceira de S\u00e3o Francisco do Porto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/\" \/>\n<meta property=\"og:site_name\" content=\"Perspetiva Atual\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-26T07:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-17T15:14:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Acr230659875520-650523.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"947\" \/>\n\t<meta property=\"og:image:height\" content=\"942\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Vitoria Girao\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/\"},\"author\":{\"name\":\"Vitoria Girao\",\"@id\":\"https:\/\/perspetivaatual.pt\/#\/schema\/person\/c90e8e11129f189f1b7588bf2888f8b5\"},\"headline\":\"Centro de Tratamento Cir\u00fargico do Linfedema em Portugal: \u201cDar esperan\u00e7a onde antes havia apenas resigna\u00e7\u00e3o\u201d\",\"datePublished\":\"2025-12-26T07:00:00+00:00\",\"dateModified\":\"2025-12-17T15:14:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/\"},\"wordCount\":3041,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/perspetivaatual.pt\/#organization\"},\"image\":{\"@id\":\"https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Acr230659875520-650523.jpg\",\"keywords\":[\"Cirurgia pl\u00e1stica\",\"Cirurgia Pl\u00e1stica Reconstrutiva Craniomaxilofacial\",\"Estomatologia\",\"Gustavo Coelho\",\"Hor\u00e1cio Costa\",\"Hospital S\u00e3o Francisco do Porto\",\"Linfedema\",\"M\u00e3o\",\"Microcirurgia e Est\u00e9tica\",\"Otorrinolaringologia\"],\"articleSection\":[\"Destaques\",\"Sa\u00fade\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/\",\"url\":\"https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/\",\"name\":\"Centro de Tratamento Cir\u00fargico do Linfedema em Portugal: \u201cDar esperan\u00e7a onde antes havia apenas resigna\u00e7\u00e3o\u201d - Perspetiva Atual\",\"isPartOf\":{\"@id\":\"https:\/\/perspetivaatual.pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Acr230659875520-650523.jpg\",\"datePublished\":\"2025-12-26T07:00:00+00:00\",\"dateModified\":\"2025-12-17T15:14:53+00:00\",\"description\":\"A vis\u00e3o pioneira do Dr. Gustavo Coelho no Hospital da Vener\u00e1vel Ordem Terceira de S\u00e3o Francisco do Porto.\",\"breadcrumb\":{\"@id\":\"https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/#primaryimage\",\"url\":\"https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Acr230659875520-650523.jpg\",\"contentUrl\":\"https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Acr230659875520-650523.jpg\",\"width\":947,\"height\":942},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/perspetivaatual.pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Centro de Tratamento Cir\u00fargico do Linfedema em Portugal: \u201cDar esperan\u00e7a onde antes havia apenas resigna\u00e7\u00e3o\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/perspetivaatual.pt\/#website\",\"url\":\"https:\/\/perspetivaatual.pt\/\",\"name\":\"Perspetiva Atual\",\"description\":\"Olhar Portugal, de diferentes formas\",\"publisher\":{\"@id\":\"https:\/\/perspetivaatual.pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/perspetivaatual.pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/perspetivaatual.pt\/#organization\",\"name\":\"Perspetiva Atual\",\"url\":\"https:\/\/perspetivaatual.pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/perspetivaatual.pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2020\/08\/cropped-perspetiva_atual-.png\",\"contentUrl\":\"https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2020\/08\/cropped-perspetiva_atual-.png\",\"width\":618,\"height\":202,\"caption\":\"Perspetiva Atual\"},\"image\":{\"@id\":\"https:\/\/perspetivaatual.pt\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/perspetivaatual.pt\/#\/schema\/person\/c90e8e11129f189f1b7588bf2888f8b5\",\"name\":\"Vitoria Girao\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/perspetivaatual.pt\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7a4a232c077ec4326004bec18e9d4616?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7a4a232c077ec4326004bec18e9d4616?s=96&d=mm&r=g\",\"caption\":\"Vitoria Girao\"},\"url\":\"https:\/\/perspetivaatual.pt\/index.php\/author\/vitoria-girao\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Centro de Tratamento Cir\u00fargico do Linfedema em Portugal: \u201cDar esperan\u00e7a onde antes havia apenas resigna\u00e7\u00e3o\u201d - Perspetiva Atual","description":"A vis\u00e3o pioneira do Dr. Gustavo Coelho no Hospital da Vener\u00e1vel Ordem Terceira de S\u00e3o Francisco do Porto.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/","og_locale":"pt_PT","og_type":"article","og_title":"Centro de Tratamento Cir\u00fargico do Linfedema em Portugal: \u201cDar esperan\u00e7a onde antes havia apenas resigna\u00e7\u00e3o\u201d - Perspetiva Atual","og_description":"A vis\u00e3o pioneira do Dr. Gustavo Coelho no Hospital da Vener\u00e1vel Ordem Terceira de S\u00e3o Francisco do Porto.","og_url":"https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/","og_site_name":"Perspetiva Atual","article_published_time":"2025-12-26T07:00:00+00:00","article_modified_time":"2025-12-17T15:14:53+00:00","og_image":[{"width":947,"height":942,"url":"https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Acr230659875520-650523.jpg","type":"image\/jpeg"}],"author":"Vitoria Girao","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":false,"Tempo estimado de leitura":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/#article","isPartOf":{"@id":"https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/"},"author":{"name":"Vitoria Girao","@id":"https:\/\/perspetivaatual.pt\/#\/schema\/person\/c90e8e11129f189f1b7588bf2888f8b5"},"headline":"Centro de Tratamento Cir\u00fargico do Linfedema em Portugal: \u201cDar esperan\u00e7a onde antes havia apenas resigna\u00e7\u00e3o\u201d","datePublished":"2025-12-26T07:00:00+00:00","dateModified":"2025-12-17T15:14:53+00:00","mainEntityOfPage":{"@id":"https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/"},"wordCount":3041,"commentCount":0,"publisher":{"@id":"https:\/\/perspetivaatual.pt\/#organization"},"image":{"@id":"https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/#primaryimage"},"thumbnailUrl":"https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Acr230659875520-650523.jpg","keywords":["Cirurgia pl\u00e1stica","Cirurgia Pl\u00e1stica Reconstrutiva Craniomaxilofacial","Estomatologia","Gustavo Coelho","Hor\u00e1cio Costa","Hospital S\u00e3o Francisco do Porto","Linfedema","M\u00e3o","Microcirurgia e Est\u00e9tica","Otorrinolaringologia"],"articleSection":["Destaques","Sa\u00fade"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/","url":"https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/","name":"Centro de Tratamento Cir\u00fargico do Linfedema em Portugal: \u201cDar esperan\u00e7a onde antes havia apenas resigna\u00e7\u00e3o\u201d - Perspetiva Atual","isPartOf":{"@id":"https:\/\/perspetivaatual.pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/#primaryimage"},"image":{"@id":"https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/#primaryimage"},"thumbnailUrl":"https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Acr230659875520-650523.jpg","datePublished":"2025-12-26T07:00:00+00:00","dateModified":"2025-12-17T15:14:53+00:00","description":"A vis\u00e3o pioneira do Dr. Gustavo Coelho no Hospital da Vener\u00e1vel Ordem Terceira de S\u00e3o Francisco do Porto.","breadcrumb":{"@id":"https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/#primaryimage","url":"https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Acr230659875520-650523.jpg","contentUrl":"https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Acr230659875520-650523.jpg","width":947,"height":942},{"@type":"BreadcrumbList","@id":"https:\/\/perspetivaatual.pt\/index.php\/2025\/12\/26\/centro-de-tratamento-cirurgico-do-linfedema-em-portugal-dar-esperanca-onde-antes-havia-apenas-resignacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/perspetivaatual.pt\/"},{"@type":"ListItem","position":2,"name":"Centro de Tratamento Cir\u00fargico do Linfedema em Portugal: \u201cDar esperan\u00e7a onde antes havia apenas resigna\u00e7\u00e3o\u201d"}]},{"@type":"WebSite","@id":"https:\/\/perspetivaatual.pt\/#website","url":"https:\/\/perspetivaatual.pt\/","name":"Perspetiva Atual","description":"Olhar Portugal, de diferentes formas","publisher":{"@id":"https:\/\/perspetivaatual.pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/perspetivaatual.pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/perspetivaatual.pt\/#organization","name":"Perspetiva Atual","url":"https:\/\/perspetivaatual.pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/perspetivaatual.pt\/#\/schema\/logo\/image\/","url":"https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2020\/08\/cropped-perspetiva_atual-.png","contentUrl":"https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2020\/08\/cropped-perspetiva_atual-.png","width":618,"height":202,"caption":"Perspetiva Atual"},"image":{"@id":"https:\/\/perspetivaatual.pt\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/perspetivaatual.pt\/#\/schema\/person\/c90e8e11129f189f1b7588bf2888f8b5","name":"Vitoria Girao","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/perspetivaatual.pt\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7a4a232c077ec4326004bec18e9d4616?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7a4a232c077ec4326004bec18e9d4616?s=96&d=mm&r=g","caption":"Vitoria Girao"},"url":"https:\/\/perspetivaatual.pt\/index.php\/author\/vitoria-girao\/"}]}},"featured_image_urls":{"full":["https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Acr230659875520-650523.jpg",947,942,false],"thumbnail":["https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Acr230659875520-650523-150x150.jpg",150,150,true],"medium":["https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Acr230659875520-650523-300x298.jpg",300,298,true],"medium_large":["https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Acr230659875520-650523-768x764.jpg",640,637,true],"large":["https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Acr230659875520-650523.jpg",640,637,false],"1536x1536":["https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Acr230659875520-650523.jpg",947,942,false],"2048x2048":["https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Acr230659875520-650523.jpg",947,942,false],"magazine-7-slider-full":["https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Acr230659875520-650523.jpg",947,942,false],"magazine-7-slider-center":["https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Acr230659875520-650523-936x897.jpg",936,897,true],"magazine-7-featured":["https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Acr230659875520-650523.jpg",947,942,false],"magazine-7-medium":["https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Acr230659875520-650523-720x380.jpg",720,380,true],"magazine-7-medium-square":["https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Acr230659875520-650523-675x450.jpg",675,450,true],"rpwe-thumbnail":["https:\/\/perspetivaatual.pt\/wp-content\/uploads\/2025\/12\/Acr230659875520-650523-45x45.jpg",45,45,true]},"author_info":{"info":[false]},"category_info":"<a href=\"https:\/\/perspetivaatual.pt\/index.php\/category\/destaques\/\" rel=\"category tag\">Destaques<\/a> <a href=\"https:\/\/perspetivaatual.pt\/index.php\/category\/saude\/\" rel=\"category tag\">Sa\u00fade<\/a>","tag_info":"Sa\u00fade","comment_count":"0","_links":{"self":[{"href":"https:\/\/perspetivaatual.pt\/index.php\/wp-json\/wp\/v2\/posts\/5170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perspetivaatual.pt\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perspetivaatual.pt\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perspetivaatual.pt\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/perspetivaatual.pt\/index.php\/wp-json\/wp\/v2\/comments?post=5170"}],"version-history":[{"count":0,"href":"https:\/\/perspetivaatual.pt\/index.php\/wp-json\/wp\/v2\/posts\/5170\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/perspetivaatual.pt\/index.php\/wp-json\/wp\/v2\/media\/5174"}],"wp:attachment":[{"href":"https:\/\/perspetivaatual.pt\/index.php\/wp-json\/wp\/v2\/media?parent=5170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perspetivaatual.pt\/index.php\/wp-json\/wp\/v2\/categories?post=5170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perspetivaatual.pt\/index.php\/wp-json\/wp\/v2\/tags?post=5170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}